{"id":29556,"date":"2020-09-15T11:54:17","date_gmt":"2020-09-15T11:54:17","guid":{"rendered":"https:\/\/solplanet.net\/installer-area\/"},"modified":"2024-03-06T03:44:01","modified_gmt":"2024-03-06T03:44:01","slug":"installer-area","status":"publish","type":"page","link":"https:\/\/solplanet.vcdev.me\/s-a\/installer-area\/","title":{"rendered":"Installer Area"},"content":{"rendered":"<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"wrapper__container\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t<div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/09\/FOTO-Featured-HomePage.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--default\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--big jumbotron__heading\">\n\tSolplanet makes things easy<\/h1><p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--big jumbotron__paragraph\">\n\tEasy-to-install, reliable and user-friendly<\/p>\t\t<\/div>\n\t<\/div>\n\n\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper  wrapper__spacing-top-large--100 wrapper__spacing-bottom-large--180\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-columns js-block-columns block-columns__gutter-large--default block-columns__vertical-spacing-large--default\">\n\t\n\n<div class=\"block-column block-column__width-large--4 block-column__width-tablet--12 \">\n\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--shaft heading__size--default block-heading__heading\">\n\tSolplanet makes things easy<\/h2>\t<\/div>\n\t<\/div>\n\n<\/div>\n\n\n\n<div class=\"block-column block-column__width-large--7 block-column__width-tablet--12 block-column__offset-large--1 block-column__offset-tablet--0 \">\n\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tSolplanet makes things easy for you. Our products are easy-to-install, reliable and<br>user-friendly.<br><br>We continue to make our products, applications and information quicker and easier to use while ensuring top performance and reliability.<br><br>This way we can reach our mission together to deliver solar to everybody.<br><\/p>\t<\/div>\n\n<\/div>\n\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--60\" id=\"video-center\">\n\t<div class=\"wrapper__anchor\" id=\"video-center\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--center heading__color--shaft heading__size--default block-heading__heading\">\n\tVideo center<\/h2>\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper  wrapper__spacing-top-large--90 wrapper__spacing-bottom-large--100\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"videos\"><\/div>\n\t\t\t<div class=\"wrapper__container\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div\n\tclass=\"block-carousel js-block-carousel swiper-container block-carousel__pagination-type-under\"\n\tdata-swiper-loop=\"1\"\n\tdata-show-items=\"2\"\n>\n\n\t<div class=\"swiper-wrapper\">\n\t\t\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/05\/20220519-InstallationVideos_Cover_ASW27-40K-LT-G3-Vaconn-DC-terminal.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tASW27 40K LT G3 Vaconn DC terminal<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17883345116a97d1af9272a\" aria-label=\"Play Video\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17883345116a97d1af9272a\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Close\" aria-label=\"Close Modal\" data-micromodal-close=\"true\">\n\t\t\tClose\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17883345116a97d1af9272a-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/t15zxnm288Q?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/05\/20220519-InstallationVideos_Cover_ASW27-40K-LT-G3-Phoenix-DC-terminal.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tASW27 40K LT G3 Phoenix DC terminal<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17883345116a97d1af92b83\" aria-label=\"Play Video\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17883345116a97d1af92b83\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Close\" aria-label=\"Close Modal\" data-micromodal-close=\"true\">\n\t\t\tClose\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17883345116a97d1af92b83-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/iDiP44LgbYw?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/05\/20220519-InstallationVideos_Cover_ASW-6-10k-S-Vaconn-DC-terminal-1.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tASW 6 10k S Vaconn DC terminal<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17883345116a97d1af92e96\" aria-label=\"Play Video\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17883345116a97d1af92e96\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Close\" aria-label=\"Close Modal\" data-micromodal-close=\"true\">\n\t\t\tClose\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17883345116a97d1af92e96-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/TJj4APZDKEA?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/05\/20220519-InstallationVideos_Cover_ASW-6-10K-S-PhoenixDCTerminal.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tASW 6 10k S Phoenix DC terminal<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17883345116a97d1af93283\" aria-label=\"Play Video\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17883345116a97d1af93283\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Close\" aria-label=\"Close Modal\" data-micromodal-close=\"true\">\n\t\t\tClose\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17883345116a97d1af93283-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/z0mbp5Sblhc?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/one-phase-installation-2.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tSingle phase installation<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17883345116a97d1af9359a\" aria-label=\"Play Video\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17883345116a97d1af9359a\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Close\" aria-label=\"Close Modal\" data-micromodal-close=\"true\">\n\t\t\tClose\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17883345116a97d1af9359a-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/EaUn9kaeC50?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/three-phase-installation-2-1.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tThree phase installation<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17883345116a97d1af9392c\" aria-label=\"Play Video\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17883345116a97d1af9392c\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Close\" aria-label=\"Close Modal\" data-micromodal-close=\"true\">\n\t\t\tClose\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17883345116a97d1af9392c-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/6GPw17R6dWU?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/01\/ASW-3-5000-H-S-Thumbnail.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--default\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--big jumbotron__paragraph\">\n\tSolplanet ASW3000 5000 H-S installation video<\/p><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17883345116a97d1af93c63\" aria-label=\"Play Video\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17883345116a97d1af93c63\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Close\" aria-label=\"Close Modal\" data-micromodal-close=\"true\">\n\t\t\tClose\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17883345116a97d1af93c63-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/Aq8Erlfe9c0?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/01\/ASW8-20K-LT-G2-Thumbnail-1.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--default\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--big jumbotron__paragraph\">\n\tSolplanet ASW8K 20K LT-G2 installation video<\/p><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17883345116a97d1af94016\" aria-label=\"Play Video\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17883345116a97d1af94016\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Close\" aria-label=\"Close Modal\" data-micromodal-close=\"true\">\n\t\t\tClose\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17883345116a97d1af94016-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/\/3BVaGCqpBUk?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/01\/ASW30-50K-LT-G2-Thumbnail.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--default\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--big jumbotron__paragraph\">\n\tSolplanet ASW30K 50K LT-G2 installation video<\/p><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17883345116a97d1af943cb\" aria-label=\"Play Video\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17883345116a97d1af943cb\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Close\" aria-label=\"Close Modal\" data-micromodal-close=\"true\">\n\t\t\tClose\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17883345116a97d1af943cb-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/Y3y_DifPydU?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/glenn-1.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tGlen installed one blindfolded<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17883345116a97d1af94720\" aria-label=\"Play Video\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17883345116a97d1af94720\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Close\" aria-label=\"Close Modal\" data-micromodal-close=\"true\">\n\t\t\tClose\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17883345116a97d1af94720-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/0b9owCCXDoo?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2021\/01\/Glen-ASW-T-Series.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--default\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--big jumbotron__paragraph\">\n\tUnboxing of<br>ASW T Series<\/p><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17883345116a97d1af94aac\" aria-label=\"Play Video\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17883345116a97d1af94aac\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Close\" aria-label=\"Close Modal\" data-micromodal-close=\"true\">\n\t\t\tClose\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17883345116a97d1af94aac-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--twentyone-nine jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/srgLj0Gvf-M?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\t<\/div>\n\n\t<div class=\"carousel-navigation carousel-navigation__theme--dark block-carousel__carousel-navigation\">\n\t<div class=\"carousel-navigation__item carousel-navigation__item--prev js-block-carousel-prev-arrow\">\n\t\t<svg class=\"carousel-navigation__icon\" width=\"22\" height=\"40\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g stroke=\"#FFF\" fill=\"none\" fill-rule=\"evenodd\" stroke-linecap=\"round\"><path d=\"M1 20L21 1M21 39L1 20\" \/><\/g><\/svg>\n\t<\/div>\n\t<div class=\"carousel-navigation__item carousel-navigation__item--next js-block-carousel-next-arrow\">\n\t\t<svg class=\"carousel-navigation__icon\" width=\"22\" height=\"40\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g stroke=\"#FFF\" fill=\"none\" fill-rule=\"evenodd\" stroke-linecap=\"round\"><path d=\"M21 20L1 1M1 39l20-19\" \/><\/g><\/svg>\n\t<\/div>\n<\/div><div class=\"carousel-pagination js-block-carousel-pagination carousel-pagination__theme--dark block-carousel__carousel-pagination\"><\/div><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper wrapper__bg-color--sand wrapper__spacing-top-large--40 wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"downloads\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-documents\">\n\t\t\t<div class=\"block-documents__intro\">\n\t\t\t<h2 class=\"heading heading__align--left heading__color--sunsetToDodger heading__size--default block-documents__heading heading__color--is-gradient\">\n\tDownload center<\/h2>\t\t<\/div>\n\t\n\t<div class=\"documents js-documents\">\n\t<div class=\"documents__filter documents-filter js-documents-placeholder\">\n\t\t<ul class=\"111  documents-filter__list js-documents-list\" data-index=\"0\">\n\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item\" data-id=\"495\" data-type=\"term\">\n\t\t\t\tDatasheets\t\t\t<\/button>\n\t\t<\/li>\n\t\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item\" data-id=\"500\" data-type=\"term\">\n\t\t\t\tInstructions\t\t\t<\/button>\n\t\t<\/li>\n\t\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item\" data-id=\"501\" data-type=\"term\">\n\t\t\t\tCertificates\t\t\t<\/button>\n\t\t<\/li>\n\t\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item is-active\" data-id=\"497\" data-type=\"term\">\n\t\t\t\tBrochures\t\t\t<\/button>\n\t\t<\/li>\n\t\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item\" data-id=\"1191\" data-type=\"term\">\n\t\t\t\tEnergy Storage System\t\t\t<\/button>\n\t\t<\/li>\n\t\t<\/ul><ul class=\"111  documents-filter__list js-documents-list\" data-index=\"1\">\n\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item\" data-id=\"58986\" data-type=\"single\">\n\t\t\t\tSol Apollo Series Brochure\t\t\t<\/button>\n\t\t<\/li>\n\t\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item is-active\" data-id=\"30008\" data-type=\"single\">\n\t\t\t\tProduct brochures\t\t\t<\/button>\n\t\t<\/li>\n\t\t<\/ul>\t<\/div>\n\t<div class=\"documents__single js-documents-details\">\n\t\t<div class=\"documents-single\">\n\t\t\t<div class=\"documents-single__title\">\n\t\t\tDownloads\t\t<\/div>\n\t\n\t<div class=\"documents-single__accordion js-accordion-downloads\">\n\t\t<div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-downloads-parent\" data-accordion-opened=\"true\">\n\t<button class=\"accordion__trigger js-accordion-downloads-trigger gtm_question_s-a\" aria-label=\"Product Brochure\">\n\t\tProduct Brochure\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-downloads-panel\" aria-hidden=\"false\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<ul class=\"documents-details\">\n\t\t\t<li class=\"documents-details__item\">\n\t\t\t<a class=\"documents-details__link\" href=\"https:\/\/solplanet.vcdev.me\/wp-content\/uploads\/2020\/11\/Global-Brochure-Solplanet-EN-0723_web-1.pdf\" download>\n\n\t\t\t\t<div class=\"documents-details__title\">\n\t\t\t\t\tSolplanet Product Brochure \t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"documents-details__version\">\n\t\t\t\t\tAug 2023\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"documents-details__language\">\n\t\t\t\t\t\tEnglish\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"documents-details__action\">\n\t\t\t\t\tpdf\t\t\t\t\t<svg class=\"documents-details__action-icon\" width=\"29\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M28.932 29.619l-.012.024a.661.661 0 01-.513.342l-.02.002-.049.002H.662a.667.667 0 01-.28-.062l-.012-.006a.66.66 0 01-.368-.544L0 29.327v-8.421a.662.662 0 011.321-.05l.002.05v7.759h26.353v-7.759a.662.662 0 011.322-.05l.002.05v8.421l-.004.049-.004.054a.657.657 0 01-.053.176l-.007.013zM14.5 0c.349 0 .635.27.66.612l.002.05-.001 20.062 6.783-6.782a.662.662 0 01.974.894l-.038.042-7.912 7.912-.01.008a.665.665 0 01-.058.05l.068-.058a.665.665 0 01-.172.124l-.01.004a.657.657 0 01-.286.065h-.017c-.011 0-.023 0-.034-.002l.051.002a.665.665 0 01-.292-.067l-.004-.002-.021-.011a.657.657 0 01-.09-.06l-.019-.015-.017-.015a.665.665 0 01-.008-.007L6.12 14.878a.662.662 0 01.894-.974l.042.038 6.782 6.782V.662c0-.366.297-.662.662-.662z\" fill=\"#555\" fill-rule=\"nonzero\" \/><\/svg>\n\t\t\t\t<\/div>\n\t\t\t<\/a>\n\n\t\t<\/li>\n          \t<\/ul>\t\t<\/div>\n\t<\/section>\n<\/div>\t<\/div>\n<\/div>\t<\/div>\n\n\t<div class=\"loader loader--use-overlay documents__loader\">\n\t<div class=\"loader__load\">\n\t\t<div class=\"loader__item loader__item--1\"><\/div>\n\t\t<div class=\"loader__item loader__item--2\"><\/div>\n\t\t<div class=\"loader__item loader__item--3\"><\/div>\n\t<\/div>\n<\/div><\/div><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0  wrapper__divider-top-large wrapper__divider-bottom-large\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"monitoring\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-cards-grid js-block-cards-grid\" data-items-per-line=3>\n\t\n<div class=\"card-simple block-card__card-simple\">\n\t\n\t\t\t\t\t<div class=\"card-simple__intro js-card-simple-intro\">\n\t\t\t\t<h2 class=\"heading heading__align--center heading__color--shaft heading__size--default card-simple__subheading\">\n\tApp Store<\/h2>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__media js-card-simple-media\">\n\t\t\t\t<img src=\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/AppStore.svg\" class=\"image card-simple__image\" \/>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__outro card-simple__outro--has-button\">\n\t\t\t\t<div class=\"btn__wrap btn__align--center card-simple__btn\">\n\t\t\t<a href=\"https:\/\/apps.apple.com\/us\/app\/ai-energy\/id1607454432\" class=\"btn btn__color--alto btn__size--default btn__size-width--default     gtm_appstore_download \" id=\"\" title=\"Download\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\tDownload\t\t<\/a>\n\t<\/div><p class=\"paragraph paragraph__color--dusty paragraph__align--center paragraph__size--default card-simple__paragraph\">\n\tConnect &amp; monitor inverters by using our native mobile apps. Download from your preferred app store.<\/p>\t\t\t<\/div>\n\t\t\n\t\t\n\t<\/div>\n\n<div class=\"card-simple block-card__card-simple\">\n\t\n\t\t\t\t\t<div class=\"card-simple__intro js-card-simple-intro\">\n\t\t\t\t<h2 class=\"heading heading__align--center heading__color--shaft heading__size--default card-simple__subheading\">\n\tGoogle Play<\/h2>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__media js-card-simple-media\">\n\t\t\t\t<img src=\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/GooglePlay.svg\" class=\"image card-simple__image\" \/>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__outro card-simple__outro--has-button\">\n\t\t\t\t<div class=\"btn__wrap btn__align--center card-simple__btn\">\n\t\t\t<a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.aiswei.international\" class=\"btn btn__color--alto btn__size--default btn__size-width--default     gtm_googleplay_download \" id=\"\" title=\" Download \" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\t Download \t\t<\/a>\n\t<\/div><p class=\"paragraph paragraph__color--dusty paragraph__align--center paragraph__size--default card-simple__paragraph\">\n\tConnect &amp; monitor inverters by using our native mobile apps. Download from your preferred app store.<\/p>\t\t\t<\/div>\n\t\t\n\t\t\n\t<\/div>\n\n<div class=\"card-simple block-card__card-simple\">\n\t\n\t\t\t\t\t<div class=\"card-simple__intro js-card-simple-intro\">\n\t\t\t\t<h2 class=\"heading heading__align--center heading__color--shaft heading__size--default card-simple__subheading\">\n\tWeb Cloud<\/h2>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__media js-card-simple-media\">\n\t\t\t\t<img src=\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Solplanet-Icon-Computer-1-e1605044361670.png\" class=\"image card-simple__image\" \/>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__outro  card-simple__outro--has-buttonpopup card-simple__outro--has-buttonpopup\">\n\t\t\t\t<div class=\"btn__wrap btn__align--center card-simple__btn btn-popup\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--default btn__size-width--default sg-popup-id-31601\" id=\" sg-popup-id-31601\" title=\"For Business Partner\" aria-label=\"\">\n\t\t\tFor Business Partner\t\t<\/a>\n\t<\/div><div class=\"btn__wrap btn__align--center card-simple__btn btn-popupn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--default btn__size-width--default sg-popup-id-37521\" id=\" sg-popup-id-37521\" title=\"For End User\" aria-label=\"\">\n\t\t\tFor End User\t\t<\/a>\n\t<\/div><p class=\"paragraph paragraph__color--dusty paragraph__align--center paragraph__size--default card-simple__paragraph\">\n\tMonitor inverters by using the web cloud. Visit our cloud service directly here.<\/p>\t\t\t<\/div>\n\t\t\n\t\t\n\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper  wrapper__spacing-top-large--80 wrapper__spacing-bottom-large--60\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"faq\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--sunsetToDodger heading__size--default block-heading__heading heading__color--is-gradient\">\n\tQuestions &amp; Answers<\/h2>\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper wrapper__bg-color--gallery  wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-faq__anchor\" id=\"faq\"><\/div>\n\n<div class=\"block-faq js-accordion\">\n\n\t\n\t<div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"true\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_s-a\" aria-label=\"Does Solplanet produce hybrid inverters?\">\n\t\tDoes Solplanet produce hybrid inverters?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"false\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tAbsolutely! We manufacture efficient, reliable, and user-friendly single and three-phase hybrid inverters tailored for solar installations in residential, commercial, and industrial settings. Explore our full product catalogue <a href=\"https:\/\/solplanet.net\/products\/\" data-type=\"URL\" data-id=\"https:\/\/solplanet.net\/products\/\">here<\/a>.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_s-a\" aria-label=\"Are Solplanet inverters protected from high-voltage surges?\">\n\t\tAre Solplanet inverters protected from high-voltage surges?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tSurge protection is a common consideration in inverter design to safeguard the equipment from voltage spikes and surges. Specific details about the surge protection features of Solplanet inverters would depend on the specific model and product specifications. It&#8217;s recommended to refer to the product documentation and user manual or contact Solplanet directly for accurate and detailed information about the surge protection capabilities of their inverters.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_s-a\" aria-label=\"How do Solplanet inverters perform in high ambient temperatures?\">\n\t\tHow do Solplanet inverters perform in high ambient temperatures?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tSolplanet inverters handle high ambient temperatures very well. They will automatically decrease power output to protect themselves from overheating. Our detailed installation and operating instructions provide specific power reduction curves for each inverter model.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_s-a\" aria-label=\"Do Solplanet inverters have a zero export control solution?\">\n\t\tDo Solplanet inverters have a zero export control solution?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tYes, they do. All of our inverters are capable of zero export once the function is set up in our convenient mobile app. You can access the export control solution via the smart meter, located directly on the inverter once you have enabled the function in the app.\u00a0<br><br>For more details, please refer to our <a href=\"\/downloads\/\" data-type=\"URL\" data-id=\"\/downloads\/\">user manuals<\/a> or <a href=\"\/contact-us\/\" data-type=\"URL\" data-id=\"\/contact-us\/\">contact<\/a> our service department for support.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_s-a\" aria-label=\"Can the PV array connected to a Solplanet inverter be oversized?\">\n\t\tCan the PV array connected to a Solplanet inverter be oversized?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tYes, it can. The PV array can typically be oversized by 150% depending on location and site irradiation levels. But note that excessive PV array oversizing can result in wasted money and a negative impact on the reliability of the inverter. If you have questions about oversizing a PV array, please contact your local Solplanet office.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_s-a\" aria-label=\"Can I use thin-film modules for Solplanet inverters?\">\n\t\tCan I use thin-film modules for Solplanet inverters?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tSolplanet inverters can be used with thin-film solar panels, but this would be a pretty rare setup. Thin-film solar panels are usually better suited for portable devices. Solplanet inverters are stationary and are designed for traditional PV arrays in residential, commercial, and industrial situations.\u00a0<br><br>However, some thin-film panels on the market do not have to be adhered to a surface and in these cases, a Solplanet inverter will operate correctly.<br><\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_s-a\" aria-label=\"Can Solplanet inverters be used in off-grid systems with a diesel generator?\">\n\t\tCan Solplanet inverters be used in off-grid systems with a diesel generator?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tNo, they cannot. Solplanet inverters are designed to be on-grid inverters. The AC side of the inverter should be connected to the utility grid at all times. There are no settings to allow the inverter to operate in an \u201coff-the-grid\u201d or \u201cisland\u201d mode. Solplanet cannot guarantee correct operation in off-grid applications and will not warranty any damages caused to the inverter(s) or the PV plant caused by off-grid use.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_s-a\" aria-label=\"Are Solplanet inverters isolated or non-isolated?\">\n\t\tAre Solplanet inverters isolated or non-isolated?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tSolplanet produces only non-isolated (transformerless) inverters. The transformerless inverter is the most common in the residential and commercial market because it usually has the highest efficiency, lowest cost, smallest size and lightest weight compared to isolated (transformer) inverters.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_s-a\" aria-label=\"Are Solplanet inverters equipped with a DC Switch?\">\n\t\tAre Solplanet inverters equipped with a DC Switch?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tYes, all Solplanet inverters are equipped with a DC switch for smooth and uninterrupted power distribution.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_s-a\" aria-label=\"How do I choose the right size inverter?\">\n\t\tHow do I choose the right size inverter?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tIn the simplest of terms, you\u2019ll want to match your inverter to the wattage of your PV array. For example, if you have a 3000-watt PV array, you\u2019ll need a 3000-watt inverter at a minimum. You\u2019ll also need to consider things like the rating of your PV array, the maximum size of the installation, and even your geographical location. But don\u2019t worry, it\u2019s not as complicated as it seems.\u00a0<br><br>Contact our technical support team for help determining which Solplanet inverter is the best match for you.<br><\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper  wrapper__spacing-top-large--30 wrapper__spacing-bottom-large--120\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t<div class=\"btn__wrap btn__align--right block-button__btn\">\n\t\t\t<a href=\"\/s-a\/questions-answers\/\" class=\"btn btn__color--alto btn__size--default btn__size-width--default \" id=\"\" title=\"Visit our full FAQ section\" aria-label=\"\">\n\t\t\tVisit our full FAQ section\t\t<\/a>\n\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--110\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"warranty\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-heading block-heading--with-image block-heading--center-mobile\">\n\t<h2 class=\"heading heading__align--left heading__color--shaft heading__size--default block-heading__heading\">\n\tOur outstanding warranty<\/h2>\t<img src=\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/10\/Screenshot-2020-10-23-at-12.49.24.png\" class=\"image block-heading__image\" \/><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--80\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-columns js-block-columns block-columns__gutter-large--big block-columns__vertical-spacing-large--big\">\n\t\n\n<div class=\"block-column block-column__width-large--4 block-column__width-tablet--12 \">\n\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--30\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--shaft heading__size--small block-heading__heading\">\n\tWarranty information<\/h2>\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tAll Solpanet products are produced according to international quality standards. We offer a standard warranty of up to 10 years without affecting the legal warranty provided by any wholesaler or retailer.<br><br><\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--center block-button__btn\">\n\t\t\t<a href=\"https:\/\/solplanet.net\/wp-content\/uploads\/2023\/09\/S-PM21-006-Factory-Quality-Warranty-Terms-for-Overseas-Territory-of-AISWEI_V2.0.pdf\" class=\"btn btn__color--alto btn__size--default btn__size-width--default \" id=\"\" title=\"Inverter warranty\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\tInverter warranty\t\t<\/a>\n\t<\/div>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--center block-button__btn\">\n\t\t\t<a href=\"https:\/\/solplanet.net\/wp-content\/uploads\/2024\/01\/s-pm21-009-battery-factory-quality-warranty-terms-for-overseas-territory-of-aiswei_v1.2.pdf\" class=\"btn btn__color--alto btn__size--default btn__size-width--default \" id=\"\" title=\"Battery warranty\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\tBattery warranty\t\t<\/a>\n\t<\/div>\t<\/div>\n\n<\/div>\n\n\n\n<div class=\"block-column block-column__width-large--4 block-column__width-tablet--12 \">\n\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--30\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--shaft heading__size--small block-heading__heading\">\n\tWarranty status<\/h2>\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tDo you want to check the warranty status of your product? We give you access to the warranty database of Solplanet\u2019s owner company AISWEI so that you can easily check the warranty status.<br><br><\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--center block-button__btn\">\n\t\t\t<a href=\"https:\/\/warranty-solplanet.aiswei-tech.com\/#\/en\/warrantySearch\" class=\"btn btn__color--alto btn__size--default btn__size-width--default \" id=\"\" title=\"Check warranty status\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\tCheck warranty status\t\t<\/a>\n\t<\/div>\t<\/div>\n\n<\/div>\n\n\n\n<div class=\"block-column block-column__width-large--4 block-column__width-tablet--12 \">\n\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--30\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--shaft heading__size--small block-heading__heading\">\n\tWarranty extension<\/h2>\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tDo you want to extend your warranty? Sign in or create an account with Solplanet\u2019s owner company AISWEI and buy a warranty extension for as little as 30\u20ac for 5 additional years or more. <br><\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--center block-button__btn\">\n\t\t\t<a href=\"https:\/\/warranty-solplanet.aiswei-tech.com\/#\/en\" class=\"btn btn__color--alto btn__size--default btn__size-width--default \" id=\"\" title=\"Get warranty extension\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\tGet warranty extension\t\t<\/a>\n\t<\/div>\t<\/div>\n\n<\/div>\n\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0  wrapper__divider-top-large\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"claims\"><\/div>\n\t\t\t<div class=\"wrapper__container  wrapper__gutter-large--none\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-card-list block-card-list__media-position--right\">\n\n\t\t\t<div class=\"block-card-list__media\">\n\t\t\t<div class=\"block-card-list__media-inner\">\n\t\t\t\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Online-Claim-page-banner-CPs2X8JYmS8-unsplash.jpg)\" class=\"image-bg block-card-list__image-bg\"><\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\n\t<div class=\"block-card-list__content\">\n\t\t<div class=\"block-card-list__content-inner\">\n\t\t\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--20\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--small block-paragraph__paragraph\">\n\tTELL US ABOUT IT<\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--sunsetToDodger heading__size--default block-heading__heading heading__color--is-gradient\">\n\tNeed to report a problem?<\/h2>\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--110\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tSolplanet products are made to last, but maybe there is an unfortunate case of a problem. Please file the claim and explain the case. Our regional teams will ensure the right local service team gets back to your shortly to address the issue.<br><\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"https:\/\/onlineclaim-solplanet.aiswei-tech.com\/#\/en\/OnlineClaim\" class=\"btn btn__color--alto btn__size--default btn__size-width--default     gtm_selectcountry \" id=\"\" title=\"Report a problem \" aria-label=\"\">\n\t\t\tReport a problem \t\t<\/a>\n\t<\/div>\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0  wrapper__divider-top-large\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"contact-us\"><\/div>\n\t\t\t<div class=\"wrapper__container  wrapper__gutter-large--none\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-card-list block-card-list__media-position--left\">\n\n\t\t\t<div class=\"block-card-list__media\">\n\t\t\t<div class=\"block-card-list__media-inner\">\n\t\t\t\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/09\/Image-component.jpg)\" class=\"image-bg block-card-list__image-bg\"><\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\n\t<div class=\"block-card-list__content\">\n\t\t<div class=\"block-card-list__content-inner\">\n\t\t\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--20\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--small block-paragraph__paragraph\">\n\t<\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--sunsetToDodger heading__size--default block-heading__heading heading__color--is-gradient\">\n\tContact us directly<\/h2>\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--110\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tShould you have an urgent problem or issue, don\u2019t hesitate to contact us directly<br><\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"\/s-a\/contact-us\/\" class=\"btn btn__color--alto btn__size--default btn__size-width--default     gtm_contactus \" id=\"\" title=\"Contact us\" aria-label=\"\">\n\t\t\tContact us\t\t<\/a>\n\t<\/div>\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0  wrapper__divider-top-large\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"distributorlist\"><\/div>\n\t\t\t<div class=\"wrapper__container  wrapper__gutter-large--none\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-card-list block-card-list__media-position--right\">\n\n\t\t\t<div class=\"block-card-list__media\">\n\t\t\t<div class=\"block-card-list__media-inner\">\n\t\t\t\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2021\/02\/marcin-jozwiak-oh0DITWoHi4-unsplash.jpg)\" class=\"image-bg block-card-list__image-bg\"><\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\n\t<div class=\"block-card-list__content\">\n\t\t<div class=\"block-card-list__content-inner\">\n\t\t\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--20\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--sunsetToDodger heading__size--default block-heading__heading heading__color--is-gradient\">\n\t<br>Find a distributor near you<\/h2>\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--110\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tContact us!<\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"\/s-a\/distributor-list\" class=\"btn btn__color--alto btn__size--default btn__size-width--default     gtm_selectcountry \" id=\"\" title=\"Distributor list\" aria-label=\"\">\n\t\t\tDistributor list\t\t<\/a>\n\t<\/div>\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Installer Area | Solplanet<\/title>\n<meta name=\"description\" content=\"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solplanet.vcdev.me\/s-a\/installer-area\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Installer Area | Solplanet\" \/>\n<meta property=\"og:description\" content=\"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solplanet.vcdev.me\/s-a\/installer-area\/\" \/>\n<meta property=\"og:site_name\" content=\"Solplanet\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-06T03:44:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/solplanet.vcdev.me\/s-a\/installer-area\/\",\"url\":\"https:\/\/solplanet.vcdev.me\/s-a\/installer-area\/\",\"name\":\"Installer Area | Solplanet\",\"isPartOf\":{\"@id\":\"https:\/\/solplanet.vcdev.me\/s-a\/#website\"},\"datePublished\":\"2020-09-15T11:54:17+00:00\",\"dateModified\":\"2024-03-06T03:44:01+00:00\",\"description\":\"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.\",\"breadcrumb\":{\"@id\":\"https:\/\/solplanet.vcdev.me\/s-a\/installer-area\/#breadcrumb\"},\"inLanguage\":\"sa-SA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/solplanet.vcdev.me\/s-a\/installer-area\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/solplanet.vcdev.me\/s-a\/installer-area\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/solplanet.vcdev.me\/s-a\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Installer Area\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/solplanet.vcdev.me\/s-a\/#website\",\"url\":\"https:\/\/solplanet.vcdev.me\/s-a\/\",\"name\":\"Solplanet\",\"description\":\"make solar for everybody\",\"publisher\":{\"@id\":\"https:\/\/solplanet.vcdev.me\/s-a\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/solplanet.vcdev.me\/s-a\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"sa-SA\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/solplanet.vcdev.me\/s-a\/#organization\",\"name\":\"Solplanet\",\"url\":\"https:\/\/solplanet.vcdev.me\/s-a\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sa-SA\",\"@id\":\"https:\/\/solplanet.vcdev.me\/s-a\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Solplanet-LinkedInIcon.jpg\",\"contentUrl\":\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Solplanet-LinkedInIcon.jpg\",\"width\":500,\"height\":500,\"caption\":\"Solplanet\"},\"image\":{\"@id\":\"https:\/\/solplanet.vcdev.me\/s-a\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Installer Area | Solplanet","description":"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solplanet.vcdev.me\/s-a\/installer-area\/","og_locale":"en_US","og_type":"article","og_title":"Installer Area | Solplanet","og_description":"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.","og_url":"https:\/\/solplanet.vcdev.me\/s-a\/installer-area\/","og_site_name":"Solplanet","article_modified_time":"2024-03-06T03:44:01+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/solplanet.vcdev.me\/s-a\/installer-area\/","url":"https:\/\/solplanet.vcdev.me\/s-a\/installer-area\/","name":"Installer Area | Solplanet","isPartOf":{"@id":"https:\/\/solplanet.vcdev.me\/s-a\/#website"},"datePublished":"2020-09-15T11:54:17+00:00","dateModified":"2024-03-06T03:44:01+00:00","description":"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.","breadcrumb":{"@id":"https:\/\/solplanet.vcdev.me\/s-a\/installer-area\/#breadcrumb"},"inLanguage":"sa-SA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solplanet.vcdev.me\/s-a\/installer-area\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/solplanet.vcdev.me\/s-a\/installer-area\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solplanet.vcdev.me\/s-a\/"},{"@type":"ListItem","position":2,"name":"Installer Area"}]},{"@type":"WebSite","@id":"https:\/\/solplanet.vcdev.me\/s-a\/#website","url":"https:\/\/solplanet.vcdev.me\/s-a\/","name":"Solplanet","description":"make solar for everybody","publisher":{"@id":"https:\/\/solplanet.vcdev.me\/s-a\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solplanet.vcdev.me\/s-a\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"sa-SA"},{"@type":"Organization","@id":"https:\/\/solplanet.vcdev.me\/s-a\/#organization","name":"Solplanet","url":"https:\/\/solplanet.vcdev.me\/s-a\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"sa-SA","@id":"https:\/\/solplanet.vcdev.me\/s-a\/#\/schema\/logo\/image\/","url":"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Solplanet-LinkedInIcon.jpg","contentUrl":"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Solplanet-LinkedInIcon.jpg","width":500,"height":500,"caption":"Solplanet"},"image":{"@id":"https:\/\/solplanet.vcdev.me\/s-a\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/solplanet.vcdev.me\/s-a\/wp-json\/wp\/v2\/pages\/29556"}],"collection":[{"href":"https:\/\/solplanet.vcdev.me\/s-a\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/solplanet.vcdev.me\/s-a\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/solplanet.vcdev.me\/s-a\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/solplanet.vcdev.me\/s-a\/wp-json\/wp\/v2\/comments?post=29556"}],"version-history":[{"count":10,"href":"https:\/\/solplanet.vcdev.me\/s-a\/wp-json\/wp\/v2\/pages\/29556\/revisions"}],"predecessor-version":[{"id":108874,"href":"https:\/\/solplanet.vcdev.me\/s-a\/wp-json\/wp\/v2\/pages\/29556\/revisions\/108874"}],"wp:attachment":[{"href":"https:\/\/solplanet.vcdev.me\/s-a\/wp-json\/wp\/v2\/media?parent=29556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}